{"id":6167,"date":"2023-03-15T11:59:19","date_gmt":"2023-03-15T11:59:19","guid":{"rendered":"https:\/\/laprensanewspaper.com\/?p=6167"},"modified":"2023-03-15T12:07:32","modified_gmt":"2023-03-15T12:07:32","slug":"proteccion-legal-en-defensa-del-inmigrante-5","status":"publish","type":"post","link":"https:\/\/laprensanewspaper.com\/index.php\/2023\/03\/15\/proteccion-legal-en-defensa-del-inmigrante-5\/","title":{"rendered":"Protecci\u00f3n Legal en Defensa del Inmigrante"},"content":{"rendered":"<figure id=\"attachment_5847\" aria-describedby=\"caption-attachment-5847\" style=\"width: 222px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-5847\" src=\"http:\/\/laprensanewspaper.com\/wp-content\/uploads\/2023\/02\/frank-krajenke-copy-222x300.jpg\" alt=\"\" width=\"222\" height=\"300\" srcset=\"https:\/\/laprensanewspaper.com\/wp-content\/uploads\/2023\/02\/frank-krajenke-copy-222x300.jpg 222w, https:\/\/laprensanewspaper.com\/wp-content\/uploads\/2023\/02\/frank-krajenke-copy.jpg 700w\" sizes=\"auto, (max-width: 222px) 100vw, 222px\" \/><figcaption id=\"caption-attachment-5847\" class=\"wp-caption-text\">Lic. Frank Krajenke, Jr.<\/figcaption><\/figure>\n<p><strong><em>Especial para La Prensa por Lic. Frank Krajenke, Jr. [#5&amp;6]<\/em><\/strong><\/p>\n<p><strong><em>VAWA<\/em><\/strong><\/p>\n<p>Requiere que la persona haya sido objeto de abuso o crueldad extrema por parte de un c\u00f3nyuge que sea ciudadano o residente permanente legal . Requiere 3 a\u00f1os de presencia continua en los Estados Unidos .<\/p>\n<p><strong><em>Asilo<\/em><\/strong><\/p>\n<p>Esta defensa requiere que una persona haya huido de su pa\u00eds porque fue perseguida o tiene un temor bien fundado de persecuci\u00f3n futura . Se ha considerado que la <em>persecuci\u00f3n <\/em>es <em>una amenaza para la vida o la libertad debido a la raza, la religi\u00f3n, la nacionalidad, la opini\u00f3n pol\u00edtica o la pertenencia a un grupo social determinado<\/em> . Tambi\u00e9n puede incluir <em>encarcelamiento injusto, amenazas de<\/em><em> violencia, tortura o negaci\u00f3n de derechos humanos b\u00e1sicos<\/em> . La persecuci\u00f3n debe provenir del gobierno o de autoridades o grupos que el gobierno no puede controlar . Debe solicitar asilo dentro de un a\u00f1o de ingresar a los Estados Unidos .<\/p>\n<p><strong><em>Retenci\u00f3n<\/em><em> de remoci\u00f3n<\/em><\/strong><\/p>\n<p><em>La<\/em> <em>retenci\u00f3n<\/em> <em>de<\/em> <em>la<\/em> <em>expulsi\u00f3n<\/em> tiene muchos de los mismos elementos que el asilo . Proh\u00edbe al gobierno de los Estados Unidos trasladar a alguien a un pa\u00eds donde su vida o libertad se ver\u00edan amenazadas a causa de un terreno protegido . Es m\u00e1s dif\u00edcil de probar porque debes mostrar una <em>probabilidad clear <\/em>de persecuci\u00f3n futura . Adem\u00e1s, la retenci\u00f3n proporciona menos beneficios que el asilo, porque los beneficiarios generalmente no son elegibles para solicitar la residencia permanente o viajar fuera de los Estados Unidos . Es un alivio no discrecional, por lo que si prueba una probabilidad clara de persecuci\u00f3n futura, el tribunal debe retener la expulsi\u00f3n . Sin embargo, aunque la deportaci\u00f3n se retiene, podr\u00eda ejecutarse m\u00e1s tarde si cambian las condiciones del pa\u00eds . Si hay una prohibici\u00f3n para el asilo, porque no lo solicit\u00f3 a tiempo, entonces la retenci\u00f3n de la deportaci\u00f3n ser\u00eda una opci\u00f3n .<\/p>\n<p><strong><em>CONVENCI\u00d3N<\/em> <em>CONTRA<\/em> <em>LA<\/em> <em>TORTURA<\/em> <em>(CAT)<\/em><\/strong><\/p>\n<p>Para calificar para la protecci\u00f3n bajo CAT, debe demostrar que es <em>m\u00e1s probable <\/em>que sea torturado si es trasladado al pa\u00eds del que reclama protecci\u00f3n . La tortura se define generalmente como <em>la imposici\u00f3n de sufrimientos f\u00edsicos y\/o mentales graves cometidos bajo el color de la ley. EL Color de la Ley, a <\/em>menudo se ha interpretado como un agente del gobierno que act\u00faa en su \u201ccapacidad oficial\u201d . Hay otro aspecto t\u00e9cnico en la Convenci\u00f3n contra la Tortura porque la esquinencia la tortura de un agente del gobierno puede constituir actuar bajo el color de la ley . La aquiescencia se ha interpretado como que el agente del gobierno est\u00e1 al tanto de la tortura por parte de terceros, pero no hace nada para evitarla en violaci\u00f3n de su responsabilidad legal de intervenir . No tiene que estar en un grupo protegido para estar protegido, como en Retenci\u00f3n o Asilo .<\/p>\n<p><strong><em>Salida <\/em><em>voluntaria<\/em><\/strong><\/p>\n<p><em>La<\/em> <em>salida<\/em> <em>voluntaria<\/em> permite a una persona salir del pa\u00eds sin una deportaci\u00f3n en su registro . Sin embargo, es posible que a\u00fan tenga una prohibici\u00f3n para regresar a los Estados Unidos dependiendo de cu\u00e1nto tiempo estuvo presente ilegalmente . Hay exenciones disponibles si de otra manera califica para regresar a los Estados Unidos en funci\u00f3n de su familia o empleo .<\/p>\n<p>Hay otras formas de alivio que incluyen <em>el ajuste de estatus<\/em>, si vino aqu\u00ed legalmente y tiene una petici\u00f3n aprobada basada en la familia o en el empleo, discreci\u00f3n procesal y acci\u00f3n diferida que requieren el acuerdo del Fiscal . Adem\u00e1s, un <em>proyecto de ley privado del Congreso <\/em>tambi\u00e9n puede detener la deportaci\u00f3n, pero esta es una forma pol\u00edtica de alivio que probablemente requerir\u00eda un caso especial de notoriedad significativa . Requerir\u00eda que alguien se comunique con un miembro del Congreso en busca de ayuda .<\/p>\n<p>Independientemente del Alivio que elija, usted re\u00fane tanta informaci\u00f3n sobre su forma de alivio como sea posible . Un abogado que practica la ley de inmigraci\u00f3n puede ayudarlo a dirigirlo . Si su problema es complejo, tambi\u00e9n puede contratar a un testigo experto para que ayude al tribunal a comprender las condiciones de su pa\u00eds o sus circunstancias particulares .<\/p>\n<p><strong><br \/>\nDelitos penales<\/strong><\/p>\n<p>Si bien todas las leyes deben ser obedecidas, hay cinco categor\u00edas principales de delitos penales que cualquier persona que busque permanecer legalmente en los Estados Unidos debe evitar absolutamente y estos son:<\/p>\n<ol>\n<li>Delitos graves agravados,<\/li>\n<li>Delitos de vileza moral (\u201cCIMT\u201d),<\/li>\n<li>Delitos de drogas,<\/li>\n<li>Delitos con armas de fuego, y<\/li>\n<li>Delitos de violencia dom\u00e9stica.<\/li>\n<\/ol>\n<p>Cabe se\u00f1alar que los delitos graves agravados prescritos por INA \u00a7 101 (a) (43), 8 USC \u00a7 1101 (a) (43) pueden excluirlo de todo tipo de reparaci\u00f3n, excepto en la Convenci\u00f3n contra la Tortura y la Retenci\u00f3n de la Expulsi\u00f3n.<\/p>\n<p><strong>Fianzas de Inmigraci\u00f3n<\/strong><\/p>\n<p>Incluso si est\u00e1 detenido, puede tener derecho a una fianza. Una fianza es un pago hecho al gobierno que garantiza que una persona acudir\u00e1 a la corte. Si no acuden a los tribunales, el dinero se perder\u00e1. En ciertas circunstancias, un extranjero detenido por el Departamento de Seguridad Nacional (DHS) puede ser liberado de la custodia tras el pago de la fianza.<\/p>\n<p>Inicialmente, el bono es establecido por el DHS. A petici\u00f3n del extranjero, un juez de inmigraci\u00f3n puede llevar a cabo una \u201caudiencia de fianza\u201d, en la que el juez de inmigraci\u00f3n tiene la autoridad para volver a determinar la cantidad de fianza establecida por el DHS.<\/p>\n<p>Los procedimientos de fianza son independientes de los procedimientos de remoci\u00f3n y las presentaciones se mantienen separadas. Es importante saberlo porque la evidencia en un caso tiene que presentarse por separado del caso en jefe. Si bien puede parecer duplicado y lo es es un indicador de pr\u00e1ctica importante para que uno no renuncie a evidencia importante en ninguna de las audiencias.<\/p>\n<p><strong>Jurisdicci\u00f3n de la Corte de Inmigraci\u00f3n sobre fianza<\/strong><\/p>\n<p>Un juez de inmigraci\u00f3n generalmente tiene jurisdicci\u00f3n para llevar a cabo una audiencia de fianza si el extranjero est\u00e1 bajo custodia del Departamento de Seguridad Nacional (DHS), excepto si un extranjero est\u00e1 en procedimientos de exclusi\u00f3n, el extranjero es un extranjero que llega, el extranjero no es elegible por motivos de seguridad o por motivos penales. El Juez de Inmigraci\u00f3n tambi\u00e9n tiene jurisdicci\u00f3n para llevar a cabo una audiencia de fianza si el extranjero es liberado de la custodia del DHS tras el pago de una fianza y, dentro de los 7 d\u00edas posteriores a la liberaci\u00f3n, presenta una solicitud de redeterminaci\u00f3n de fianza ante el Tribunal de Inmigraci\u00f3n.<\/p>\n<p>Un juez de inmigraci\u00f3n tiene jurisdicci\u00f3n sobre tales casos, incluso si no se ha presentado un documento de acusaci\u00f3n. Adem\u00e1s, un juez de inmigraci\u00f3n tiene jurisdicci\u00f3n para decidir si \u00e9l o ella tiene jurisdicci\u00f3n para llevar a cabo una audiencia de fianza.<\/p>\n<p><em>C\u00f3mo<\/em> <em>solicitar<\/em><em> una fianza<\/em><\/p>\n<p>Una solicitud para una audiencia de fianza se puede hacer por escrito o se puede hacer oralmente en la corte o, a discreci\u00f3n del Juez de Inmigraci\u00f3n, por tel\u00e9fono. Si est\u00e1 disponible, se debe proporcionar una copia del Aviso de comparecencia (<em>Formulario I-862<\/em>). El n\u00famero de tel\u00e9fono de cada Corte de Inmigraci\u00f3n aparece en el sitio web <em>de la Oficina Ejecutiva de Revisi\u00f3n de Inmigraci\u00f3n <\/em>en <a href=\"http:\/\/www.justice.gov\/eoir\"><em>www.justice.gov\/eoir<\/em><\/a>.<\/p>\n<p>El contenido de una solicitud de audiencia de fianza debe indicar:<\/p>\n<ol>\n<li><em>el<\/em> <em>nombre<\/em> <em>completo<\/em> <em>y<\/em> <em>el<\/em> <em>n\u00famero<\/em> <em>de<\/em> <em>registro<\/em> <em>de<\/em> <em>extranjero<\/em> <em>(\u201cN\u00famero<\/em> <em>A\u201d) <\/em><em>del extranjero<\/em><\/li>\n<li><em>el monto de la fianza establecido por el Departamento de Seguridad Nacional<\/em><\/li>\n<li><em>si<\/em> <em>el<\/em> <em>extranjero<\/em> <em>est\u00e1<\/em> <em>detenido,<\/em> <em>la<\/em> <em>ubicaci\u00f3n<\/em> <em>del<\/em> <em>centro<\/em> <em>de<\/em> <em>detenci\u00f3n<\/em><\/li>\n<\/ol>\n<p>No hay tarifa de presentaci\u00f3n para solicitar una audiencia de fianza.<\/p>\n<p><em>D\u00f3nde<\/em><em> solicitar una fianza<\/em><\/p>\n<p>Una solicitud de audiencia de fianza se hace, en orden de preferencia, para:<\/p>\n<ol>\n<li><em>si el extranjero es detenido, el Tribunal de Inmigraci\u00f3n que tenga jurisdicci\u00f3n sobre el lugar de detenci\u00f3n del extranjero<\/em>;<\/li>\n<li><em>el<\/em> <em>Tribunal<\/em> <em>de<\/em> <em>Inmigraci\u00f3n<\/em> <em>con<\/em> <em>control<\/em> <em>administrativo<\/em> <em>sobre<\/em> <em>el<\/em> <em>caso<\/em>; o<\/li>\n<li><em>la Oficina del Juez Principal de Inmigraci\u00f3n para la designaci\u00f3n de un Tribunal de Inmigraci\u00f3n<\/em><\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<div class=\"responsive-container\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"QdRpaXdl76\"><p><a href=\"https:\/\/laprensanewspaper.com\/index.php\/2023\/03\/01\/proteccion-legal-en-defensa-del-inmigrante-4\/\">Protecci\u00f3n Legal en Defensa del Inmigrante<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;Protecci\u00f3n Legal en Defensa del Inmigrante&#8221; &#8212; La Prensa Newspaper\" src=\"https:\/\/laprensanewspaper.com\/index.php\/2023\/03\/01\/proteccion-legal-en-defensa-del-inmigrante-4\/embed\/#?secret=aEhJsobENE#?secret=QdRpaXdl76\" data-secret=\"QdRpaXdl76\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Especial para La Prensa por Lic. Frank Krajenke, Jr. [#5&amp;6] VAWA Requiere que la persona haya sido objeto de abuso o crueldad extrema por parte de un c\u00f3nyuge que sea ciudadano o residente permanente legal . Requiere 3 a\u00f1os de presencia continua en los Estados Unidos . Asilo Esta defensa requiere que una persona haya<\/p>\n","protected":false},"author":2,"featured_media":5891,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_rtcl_gb_attr":"","footnotes":""},"categories":[6],"tags":[],"wf_post_folders":[133],"class_list":["post-6167","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articles"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Especial para La Prensa por Lic. Frank Krajenke, Jr. [#5&amp;6] VAWA Requiere que la persona haya sido objeto de abuso o crueldad extrema por parte de un c\u00f3nyuge que sea ciudadano o residente permanente legal . Requiere 3 a\u00f1os de presencia continua en los Estados Unidos . Asilo Esta defensa requiere que una persona haya\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"LaPrensa Newspaper\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/laprensanewspaper.com\/index.php\/2023\/03\/15\/proteccion-legal-en-defensa-del-inmigrante-5\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"La Prensa Newspaper - Ohio &amp; Michigan&#039;s Oldest Biligual Latino Newspaper\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Protecci\u00f3n Legal en Defensa del Inmigrante - La Prensa Newspaper\" \/>\n\t\t<meta property=\"og:description\" content=\"Especial para La Prensa por Lic. Frank Krajenke, Jr. [#5&amp;6] VAWA Requiere que la persona haya sido objeto de abuso o crueldad extrema por parte de un c\u00f3nyuge que sea ciudadano o residente permanente legal . Requiere 3 a\u00f1os de presencia continua en los Estados Unidos . Asilo Esta defensa requiere que una persona haya\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/laprensanewspaper.com\/index.php\/2023\/03\/15\/proteccion-legal-en-defensa-del-inmigrante-5\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/laprensanewspaper.com\/wp-content\/uploads\/2022\/02\/La-Prensa-Logo-clear.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/laprensanewspaper.com\/wp-content\/uploads\/2022\/02\/La-Prensa-Logo-clear.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-03-15T11:59:19+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-03-15T12:07:32+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/prensa1\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/prensa1\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@LaPrensa16\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Protecci\u00f3n Legal en Defensa del Inmigrante - La Prensa Newspaper\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Especial para La Prensa por Lic. Frank Krajenke, Jr. [#5&amp;6] VAWA Requiere que la persona haya sido objeto de abuso o crueldad extrema por parte de un c\u00f3nyuge que sea ciudadano o residente permanente legal . Requiere 3 a\u00f1os de presencia continua en los Estados Unidos . Asilo Esta defensa requiere que una persona haya\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@LaPrensa16\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/laprensanewspaper.com\/wp-content\/uploads\/2022\/02\/La-Prensa-Logo-clear.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/laprensanewspaper.com\\\/index.php\\\/2023\\\/03\\\/15\\\/proteccion-legal-en-defensa-del-inmigrante-5\\\/#blogposting\",\"name\":\"Protecci\\u00f3n Legal en Defensa del Inmigrante - La Prensa Newspaper\",\"headline\":\"Protecci\\u00f3n Legal en Defensa del Inmigrante\",\"author\":{\"@id\":\"https:\\\/\\\/laprensanewspaper.com\\\/index.php\\\/author\\\/laprensa\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/laprensanewspaper.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/laprensanewspaper.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Frank-Krajenke.jpg\",\"width\":700,\"height\":411},\"datePublished\":\"2023-03-15T11:59:19+00:00\",\"dateModified\":\"2023-03-15T12:07:32+00:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/laprensanewspaper.com\\\/index.php\\\/2023\\\/03\\\/15\\\/proteccion-legal-en-defensa-del-inmigrante-5\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/laprensanewspaper.com\\\/index.php\\\/2023\\\/03\\\/15\\\/proteccion-legal-en-defensa-del-inmigrante-5\\\/#webpage\"},\"articleSection\":\"Articles, 031723\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/laprensanewspaper.com\\\/index.php\\\/2023\\\/03\\\/15\\\/proteccion-legal-en-defensa-del-inmigrante-5\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/laprensanewspaper.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/laprensanewspaper.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/laprensanewspaper.com\\\/index.php\\\/category\\\/articles\\\/#listItem\",\"name\":\"Articles\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/laprensanewspaper.com\\\/index.php\\\/category\\\/articles\\\/#listItem\",\"position\":2,\"name\":\"Articles\",\"item\":\"https:\\\/\\\/laprensanewspaper.com\\\/index.php\\\/category\\\/articles\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/laprensanewspaper.com\\\/index.php\\\/2023\\\/03\\\/15\\\/proteccion-legal-en-defensa-del-inmigrante-5\\\/#listItem\",\"name\":\"Protecci\\u00f3n Legal en Defensa del Inmigrante\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/laprensanewspaper.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/laprensanewspaper.com\\\/index.php\\\/2023\\\/03\\\/15\\\/proteccion-legal-en-defensa-del-inmigrante-5\\\/#listItem\",\"position\":3,\"name\":\"Protecci\\u00f3n Legal en Defensa del Inmigrante\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/laprensanewspaper.com\\\/index.php\\\/category\\\/articles\\\/#listItem\",\"name\":\"Articles\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/laprensanewspaper.com\\\/#organization\",\"name\":\"La Prensa Newspaper\",\"description\":\"Ohio & Michigan's Oldest Biligual Latino Newspaper\",\"url\":\"https:\\\/\\\/laprensanewspaper.com\\\/\",\"telephone\":\"+14198702797\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/laprensanewspaper.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/La-Prensa-Logo-copy.png\",\"@id\":\"https:\\\/\\\/laprensanewspaper.com\\\/index.php\\\/2023\\\/03\\\/15\\\/proteccion-legal-en-defensa-del-inmigrante-5\\\/#organizationLogo\",\"width\":685,\"height\":169},\"image\":{\"@id\":\"https:\\\/\\\/laprensanewspaper.com\\\/index.php\\\/2023\\\/03\\\/15\\\/proteccion-legal-en-defensa-del-inmigrante-5\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/prensa1\",\"https:\\\/\\\/twitter.com\\\/LaPrensa16\",\"https:\\\/\\\/www.instagram.com\\\/laprensa1\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/laprensanewspaper.com\\\/index.php\\\/author\\\/laprensa\\\/#author\",\"url\":\"https:\\\/\\\/laprensanewspaper.com\\\/index.php\\\/author\\\/laprensa\\\/\",\"name\":\"LaPrensa Newspaper\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/prensa1\",\"https:\\\/\\\/twitter.com\\\/LaPrensa16\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/laprensanewspaper.com\\\/index.php\\\/2023\\\/03\\\/15\\\/proteccion-legal-en-defensa-del-inmigrante-5\\\/#webpage\",\"url\":\"https:\\\/\\\/laprensanewspaper.com\\\/index.php\\\/2023\\\/03\\\/15\\\/proteccion-legal-en-defensa-del-inmigrante-5\\\/\",\"name\":\"Protecci\\u00f3n Legal en Defensa del Inmigrante - La Prensa Newspaper\",\"description\":\"Especial para La Prensa por Lic. Frank Krajenke, Jr. [#5&6] VAWA Requiere que la persona haya sido objeto de abuso o crueldad extrema por parte de un c\\u00f3nyuge que sea ciudadano o residente permanente legal . Requiere 3 a\\u00f1os de presencia continua en los Estados Unidos . Asilo Esta defensa requiere que una persona haya\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/laprensanewspaper.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/laprensanewspaper.com\\\/index.php\\\/2023\\\/03\\\/15\\\/proteccion-legal-en-defensa-del-inmigrante-5\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/laprensanewspaper.com\\\/index.php\\\/author\\\/laprensa\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/laprensanewspaper.com\\\/index.php\\\/author\\\/laprensa\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/laprensanewspaper.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Frank-Krajenke.jpg\",\"@id\":\"https:\\\/\\\/laprensanewspaper.com\\\/index.php\\\/2023\\\/03\\\/15\\\/proteccion-legal-en-defensa-del-inmigrante-5\\\/#mainImage\",\"width\":700,\"height\":411},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/laprensanewspaper.com\\\/index.php\\\/2023\\\/03\\\/15\\\/proteccion-legal-en-defensa-del-inmigrante-5\\\/#mainImage\"},\"datePublished\":\"2023-03-15T11:59:19+00:00\",\"dateModified\":\"2023-03-15T12:07:32+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/laprensanewspaper.com\\\/#website\",\"url\":\"https:\\\/\\\/laprensanewspaper.com\\\/\",\"name\":\"La Prensa Newspaper\",\"description\":\"Ohio & Michigan's Oldest Biligual Latino Newspaper\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/laprensanewspaper.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Protecci\u00f3n Legal en Defensa del Inmigrante - La Prensa Newspaper","description":"Especial para La Prensa por Lic. Frank Krajenke, Jr. [#5&6] VAWA Requiere que la persona haya sido objeto de abuso o crueldad extrema por parte de un c\u00f3nyuge que sea ciudadano o residente permanente legal . Requiere 3 a\u00f1os de presencia continua en los Estados Unidos . Asilo Esta defensa requiere que una persona haya","canonical_url":"https:\/\/laprensanewspaper.com\/index.php\/2023\/03\/15\/proteccion-legal-en-defensa-del-inmigrante-5\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/laprensanewspaper.com\/index.php\/2023\/03\/15\/proteccion-legal-en-defensa-del-inmigrante-5\/#blogposting","name":"Protecci\u00f3n Legal en Defensa del Inmigrante - La Prensa Newspaper","headline":"Protecci\u00f3n Legal en Defensa del Inmigrante","author":{"@id":"https:\/\/laprensanewspaper.com\/index.php\/author\/laprensa\/#author"},"publisher":{"@id":"https:\/\/laprensanewspaper.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/laprensanewspaper.com\/wp-content\/uploads\/2023\/02\/Frank-Krajenke.jpg","width":700,"height":411},"datePublished":"2023-03-15T11:59:19+00:00","dateModified":"2023-03-15T12:07:32+00:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/laprensanewspaper.com\/index.php\/2023\/03\/15\/proteccion-legal-en-defensa-del-inmigrante-5\/#webpage"},"isPartOf":{"@id":"https:\/\/laprensanewspaper.com\/index.php\/2023\/03\/15\/proteccion-legal-en-defensa-del-inmigrante-5\/#webpage"},"articleSection":"Articles, 031723"},{"@type":"BreadcrumbList","@id":"https:\/\/laprensanewspaper.com\/index.php\/2023\/03\/15\/proteccion-legal-en-defensa-del-inmigrante-5\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/laprensanewspaper.com#listItem","position":1,"name":"Home","item":"https:\/\/laprensanewspaper.com","nextItem":{"@type":"ListItem","@id":"https:\/\/laprensanewspaper.com\/index.php\/category\/articles\/#listItem","name":"Articles"}},{"@type":"ListItem","@id":"https:\/\/laprensanewspaper.com\/index.php\/category\/articles\/#listItem","position":2,"name":"Articles","item":"https:\/\/laprensanewspaper.com\/index.php\/category\/articles\/","nextItem":{"@type":"ListItem","@id":"https:\/\/laprensanewspaper.com\/index.php\/2023\/03\/15\/proteccion-legal-en-defensa-del-inmigrante-5\/#listItem","name":"Protecci\u00f3n Legal en Defensa del Inmigrante"},"previousItem":{"@type":"ListItem","@id":"https:\/\/laprensanewspaper.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/laprensanewspaper.com\/index.php\/2023\/03\/15\/proteccion-legal-en-defensa-del-inmigrante-5\/#listItem","position":3,"name":"Protecci\u00f3n Legal en Defensa del Inmigrante","previousItem":{"@type":"ListItem","@id":"https:\/\/laprensanewspaper.com\/index.php\/category\/articles\/#listItem","name":"Articles"}}]},{"@type":"Organization","@id":"https:\/\/laprensanewspaper.com\/#organization","name":"La Prensa Newspaper","description":"Ohio & Michigan's Oldest Biligual Latino Newspaper","url":"https:\/\/laprensanewspaper.com\/","telephone":"+14198702797","logo":{"@type":"ImageObject","url":"https:\/\/laprensanewspaper.com\/wp-content\/uploads\/2022\/02\/La-Prensa-Logo-copy.png","@id":"https:\/\/laprensanewspaper.com\/index.php\/2023\/03\/15\/proteccion-legal-en-defensa-del-inmigrante-5\/#organizationLogo","width":685,"height":169},"image":{"@id":"https:\/\/laprensanewspaper.com\/index.php\/2023\/03\/15\/proteccion-legal-en-defensa-del-inmigrante-5\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/prensa1","https:\/\/twitter.com\/LaPrensa16","https:\/\/www.instagram.com\/laprensa1\/"]},{"@type":"Person","@id":"https:\/\/laprensanewspaper.com\/index.php\/author\/laprensa\/#author","url":"https:\/\/laprensanewspaper.com\/index.php\/author\/laprensa\/","name":"LaPrensa Newspaper","sameAs":["https:\/\/www.facebook.com\/prensa1","https:\/\/twitter.com\/LaPrensa16"]},{"@type":"WebPage","@id":"https:\/\/laprensanewspaper.com\/index.php\/2023\/03\/15\/proteccion-legal-en-defensa-del-inmigrante-5\/#webpage","url":"https:\/\/laprensanewspaper.com\/index.php\/2023\/03\/15\/proteccion-legal-en-defensa-del-inmigrante-5\/","name":"Protecci\u00f3n Legal en Defensa del Inmigrante - La Prensa Newspaper","description":"Especial para La Prensa por Lic. Frank Krajenke, Jr. [#5&6] VAWA Requiere que la persona haya sido objeto de abuso o crueldad extrema por parte de un c\u00f3nyuge que sea ciudadano o residente permanente legal . Requiere 3 a\u00f1os de presencia continua en los Estados Unidos . Asilo Esta defensa requiere que una persona haya","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/laprensanewspaper.com\/#website"},"breadcrumb":{"@id":"https:\/\/laprensanewspaper.com\/index.php\/2023\/03\/15\/proteccion-legal-en-defensa-del-inmigrante-5\/#breadcrumblist"},"author":{"@id":"https:\/\/laprensanewspaper.com\/index.php\/author\/laprensa\/#author"},"creator":{"@id":"https:\/\/laprensanewspaper.com\/index.php\/author\/laprensa\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/laprensanewspaper.com\/wp-content\/uploads\/2023\/02\/Frank-Krajenke.jpg","@id":"https:\/\/laprensanewspaper.com\/index.php\/2023\/03\/15\/proteccion-legal-en-defensa-del-inmigrante-5\/#mainImage","width":700,"height":411},"primaryImageOfPage":{"@id":"https:\/\/laprensanewspaper.com\/index.php\/2023\/03\/15\/proteccion-legal-en-defensa-del-inmigrante-5\/#mainImage"},"datePublished":"2023-03-15T11:59:19+00:00","dateModified":"2023-03-15T12:07:32+00:00"},{"@type":"WebSite","@id":"https:\/\/laprensanewspaper.com\/#website","url":"https:\/\/laprensanewspaper.com\/","name":"La Prensa Newspaper","description":"Ohio & Michigan's Oldest Biligual Latino Newspaper","inLanguage":"en-US","publisher":{"@id":"https:\/\/laprensanewspaper.com\/#organization"}}]},"og:locale":"en_US","og:site_name":"La Prensa Newspaper - Ohio &amp; Michigan's Oldest Biligual Latino Newspaper","og:type":"article","og:title":"Protecci\u00f3n Legal en Defensa del Inmigrante - La Prensa Newspaper","og:description":"Especial para La Prensa por Lic. Frank Krajenke, Jr. [#5&amp;6] VAWA Requiere que la persona haya sido objeto de abuso o crueldad extrema por parte de un c\u00f3nyuge que sea ciudadano o residente permanente legal . Requiere 3 a\u00f1os de presencia continua en los Estados Unidos . Asilo Esta defensa requiere que una persona haya","og:url":"https:\/\/laprensanewspaper.com\/index.php\/2023\/03\/15\/proteccion-legal-en-defensa-del-inmigrante-5\/","og:image":"https:\/\/laprensanewspaper.com\/wp-content\/uploads\/2022\/02\/La-Prensa-Logo-clear.png","og:image:secure_url":"https:\/\/laprensanewspaper.com\/wp-content\/uploads\/2022\/02\/La-Prensa-Logo-clear.png","article:published_time":"2023-03-15T11:59:19+00:00","article:modified_time":"2023-03-15T12:07:32+00:00","article:publisher":"https:\/\/www.facebook.com\/prensa1","article:author":"https:\/\/www.facebook.com\/prensa1","twitter:card":"summary","twitter:site":"@LaPrensa16","twitter:title":"Protecci\u00f3n Legal en Defensa del Inmigrante - La Prensa Newspaper","twitter:description":"Especial para La Prensa por Lic. Frank Krajenke, Jr. [#5&amp;6] VAWA Requiere que la persona haya sido objeto de abuso o crueldad extrema por parte de un c\u00f3nyuge que sea ciudadano o residente permanente legal . Requiere 3 a\u00f1os de presencia continua en los Estados Unidos . Asilo Esta defensa requiere que una persona haya","twitter:creator":"@LaPrensa16","twitter:image":"https:\/\/laprensanewspaper.com\/wp-content\/uploads\/2022\/02\/La-Prensa-Logo-clear.png"},"aioseo_meta_data":{"post_id":"6167","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-03-15 11:59:19","updated":"2025-06-04 14:48:24","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"rttpg_featured_image_url":{"full":["https:\/\/laprensanewspaper.com\/wp-content\/uploads\/2023\/02\/Frank-Krajenke.jpg",700,411,false],"landscape":["https:\/\/laprensanewspaper.com\/wp-content\/uploads\/2023\/02\/Frank-Krajenke.jpg",700,411,false],"portraits":["https:\/\/laprensanewspaper.com\/wp-content\/uploads\/2023\/02\/Frank-Krajenke.jpg",700,411,false],"thumbnail":["https:\/\/laprensanewspaper.com\/wp-content\/uploads\/2023\/02\/Frank-Krajenke-150x150.jpg",150,150,true],"medium":["https:\/\/laprensanewspaper.com\/wp-content\/uploads\/2023\/02\/Frank-Krajenke-300x176.jpg",300,176,true],"large":["https:\/\/laprensanewspaper.com\/wp-content\/uploads\/2023\/02\/Frank-Krajenke.jpg",640,376,false],"1536x1536":["https:\/\/laprensanewspaper.com\/wp-content\/uploads\/2023\/02\/Frank-Krajenke.jpg",700,411,false],"2048x2048":["https:\/\/laprensanewspaper.com\/wp-content\/uploads\/2023\/02\/Frank-Krajenke.jpg",700,411,false],"rtcl-gallery":["https:\/\/laprensanewspaper.com\/wp-content\/uploads\/2023\/02\/Frank-Krajenke.jpg",700,411,false],"rtcl-thumbnail":["https:\/\/laprensanewspaper.com\/wp-content\/uploads\/2023\/02\/Frank-Krajenke-320x240.jpg",320,240,true],"rtcl-gallery-thumbnail":["https:\/\/laprensanewspaper.com\/wp-content\/uploads\/2023\/02\/Frank-Krajenke-150x105.jpg",150,105,true],"psacp-medium":["https:\/\/laprensanewspaper.com\/wp-content\/uploads\/2023\/02\/Frank-Krajenke.jpg",500,294,false],"rpwe-thumbnail":["https:\/\/laprensanewspaper.com\/wp-content\/uploads\/2023\/02\/Frank-Krajenke-45x45.jpg",45,45,true]},"rttpg_author":{"display_name":"LaPrensa Newspaper","author_link":"https:\/\/laprensanewspaper.com\/index.php\/author\/laprensa\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/laprensanewspaper.com\/index.php\/category\/articles\/\" rel=\"category tag\">Articles<\/a>","rttpg_excerpt":"Especial para La Prensa por Lic. Frank Krajenke, Jr. [#5&amp;6] VAWA Requiere que la persona haya sido objeto de abuso o crueldad extrema por parte de un c\u00f3nyuge que sea ciudadano o residente permanente legal . Requiere 3 a\u00f1os de presencia continua en los Estados Unidos . Asilo Esta defensa requiere que una persona haya","_links":{"self":[{"href":"https:\/\/laprensanewspaper.com\/index.php\/wp-json\/wp\/v2\/posts\/6167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laprensanewspaper.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laprensanewspaper.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laprensanewspaper.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laprensanewspaper.com\/index.php\/wp-json\/wp\/v2\/comments?post=6167"}],"version-history":[{"count":4,"href":"https:\/\/laprensanewspaper.com\/index.php\/wp-json\/wp\/v2\/posts\/6167\/revisions"}],"predecessor-version":[{"id":6175,"href":"https:\/\/laprensanewspaper.com\/index.php\/wp-json\/wp\/v2\/posts\/6167\/revisions\/6175"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laprensanewspaper.com\/index.php\/wp-json\/wp\/v2\/media\/5891"}],"wp:attachment":[{"href":"https:\/\/laprensanewspaper.com\/index.php\/wp-json\/wp\/v2\/media?parent=6167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laprensanewspaper.com\/index.php\/wp-json\/wp\/v2\/categories?post=6167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laprensanewspaper.com\/index.php\/wp-json\/wp\/v2\/tags?post=6167"},{"taxonomy":"wf_post_folders","embeddable":true,"href":"https:\/\/laprensanewspaper.com\/index.php\/wp-json\/wp\/v2\/wf_post_folders?post=6167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}